{"id":369654,"date":"2026-05-20T11:09:25","date_gmt":"2026-05-20T09:09:25","guid":{"rendered":"https:\/\/digalco.com\/tienda\/eizo-flexscan-ev2316w-23-led-169-reconditionne-1920x1080-fr-15036\/"},"modified":"2026-05-25T13:24:28","modified_gmt":"2026-05-25T11:24:28","slug":"eizo-flexscan-ev2316w-23-led-169-reconditionne-1920x1080-fr-15036","status":"publish","type":"product","link":"https:\/\/digalco.com\/fr\/produit\/eizo-flexscan-ev2316w-23-led-169-reconditionne-1920x1080-fr-15036\/","title":{"rendered":"Eizo FlexScan EV2316W 23\u00a0\u00bb Led 16:9 | Reconditionn\u00e9 | 1920&#215;1080"},"content":{"rendered":"<p><strong>\u00c9cran<\/strong><br \/>Led 23 \u00a0\u00bb FullHD avec Haut-parleurs \u00b7  16:9  \u00b7 R\u00e9solution 1920&#215;1080<br \/>Dot pitch 0.265 mm<br \/>R\u00e9ponse 5 ms<br \/>Contraste 1000:1<br \/>Luminosit\u00e9 250 cd\/m2<br \/>Angle vision 170\u00b0v\/160\u00b0h<br \/><strong>Ports vid\u00e9o<\/strong><br \/>VGA<br \/>Display Port<br \/>DVI<br \/><strong>Affichage sp\u00e9cifique<\/strong><br \/>Stand VESA<br \/>Base<br \/>R\u00e9glable en hauteur<br \/><strong>Autres<\/strong><br \/>hR emballage<br \/><strong>Dimensions<\/strong><br \/>56x32x23 cm.<br \/><strong>Poids<\/strong><br \/>4.00 Kg.<br \/><strong>Sp\u00e9cifications suppl\u00e9mentaires<\/strong><br \/>L&rsquo;Eizo FlexScan EV2316W est un moniteur LED professionnel de 23 pouces de la c\u00e9l\u00e8bre marque japonaise Eizo, r\u00e9f\u00e9rence mondiale en mati\u00e8re de qualit\u00e9, d&rsquo;ergonomie et de fiabilit\u00e9 pour les environnements de travail exigeants. Il offre une r\u00e9solution Full HD de 1920&#215;1080 pixels au format 16:9 avec un pas de masque de 0,265 mm, garantissant une image nette, d\u00e9taill\u00e9e et confortable pour de longues journ\u00e9es de travail devant l&rsquo;\u00e9cran. Le temps de r\u00e9ponse de 5 ms et le taux de contraste de 1000:1 assurent un affichage clair et bien d\u00e9fini sur tous types de contenus, soutenus par une luminosit\u00e9 de 250 cd\/m\u00b2 qui offre une image \u00e9quilibr\u00e9e et reposante dans les conditions d&rsquo;\u00e9clairage de bureau habituelles. L&rsquo;angle de vision atteint 170\u00b0 en vertical et 160\u00b0 en horizontal, offrant une visibilit\u00e9 correcte et confortable depuis diff\u00e9rentes positions de travail. Il int\u00e8gre des haut-parleurs qui ajoutent une fonctionnalit\u00e9 audio sans n\u00e9cessiter de p\u00e9riph\u00e9riques suppl\u00e9mentaires. La connectivit\u00e9 comprend des entr\u00e9es VGA, DisplayPort et DVI, ainsi que deux ports USB 2.0 pour connecter des appareils suppl\u00e9mentaires directement depuis le moniteur. L&rsquo;\u00e9quipement est livr\u00e9 avec un c\u00e2ble d&rsquo;alimentation et un c\u00e2ble VGA inclus, pr\u00eat \u00e0 l&#8217;emploi imm\u00e9diat. Un moniteur professionnel Eizo reconditionn\u00e9, synonyme de qualit\u00e9 de fabrication et de fiabilit\u00e9 \u00e9prouv\u00e9e, id\u00e9al pour les environnements de travail qui exigent le meilleur en ergonomie visuelle et en performance durable.<br \/>Bel aspect ext\u00e9rieur. Peut pr\u00e9senter de l\u00e9g\u00e8res traces d&rsquo;utilisation sur le bo\u00eetier. Si vous avez des questions, appelez-nous ou utilisez notre chat pour obtenir plus d&rsquo;informations ou pour demander des d\u00e9tails suppl\u00e9mentaires.<\/p>\n<p><strong>Commentaires<\/strong><br \/><u>2xUSB 2.0 &#8211; C\u00e2ble d&rsquo;alimentation et VGA inclus<\/u><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Led 23 \u00a0\u00bb FullHD avec Haut-parleurs \u00b7 16:9 \u00b7 Dot pitch 0.265 mm \u00b7 R\u00e9ponse 5 ms \u00b7 Contraste 1000:1 \u00b7 Luminosit\u00e9 250 cd\/m2 \u00b7 VGA \u00b7 Display Port \u00b7 DVI \u00b7<br \/>\n<u>2xUSB 2.0 &#8211; C\u00e2ble d&rsquo;alimentation et VGA inclus<\/u> [&#8230;]<\/p>\n<p><a class=\"btn btn-secondary understrap-read-more-link\" href=\"https:\/\/digalco.com\/fr\/produit\/eizo-flexscan-ev2316w-23-led-169-reconditionne-1920x1080-fr-15036\/\">Lire la suite\u2026<span class=\"screen-reader-text\"> from Eizo FlexScan EV2316W 23\u00a0\u00bb Led 16:9 | Reconditionn\u00e9 | 1920&#215;1080<\/span><\/a><\/p>\n","protected":false},"featured_media":369579,"template":"","meta":[],"product_brand":[3902],"product_cat":[1493,2386],"product_tag":[],"class_list":["post-369654","product","type-product","status-publish","has-post-thumbnail","product_brand-eizo","product_cat-moniteurs-fr","product_cat-moniteurs-23-fr","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"bundled_by":[],"bundle_stock_status":"outofstock","bundle_stock_quantity":0,"bundle_virtual":false,"bundle_layout":"","bundle_add_to_cart_form_location":"","bundle_editable_in_cart":false,"bundle_sold_individually_context":"","bundle_item_grouping":"","bundle_min_size":"","bundle_max_size":"","bundle_price":[],"bundled_items":[],"bundle_sell_ids":[],"exclude_global_add_ons":true,"addons":{"hdmi-upgrades":{"name":"Extension c\u00e2ble","type":"multiple_choice","position":0,"required":false,"title_format":"heading","default":"","description_enable":false,"description":"","placeholder_enable":false,"placeholder":"","display":"radiobutton","restrictions_type":"any_text","adjust_price":false,"price":"","price_type":"quantity_based","restrictions":false,"min":"0","max":"0","options":[{"label":"C\u00e2ble DisplayPort vers DisplayPort 1,8 mts. [AMP00103]","price":"8.0000","price_type":"quantity_based","image":0,"visibility":true},{"label":"C\u00e2ble DVI-D M\/M Dual Link 1,8 mts. [AMP00102]","price":"2.0000","price_type":"quantity_based","image":0,"visibility":true}]}},"df_price":82,"df_sale_price":"","df_regular_price":82,"df_image_link":"https:\/\/digalco.com\/wp-content\/uploads\/images\/product\/15036\/eizo00044_01-300x225.jpg","_links":{"self":[{"href":"https:\/\/digalco.com\/fr\/wp-json\/wp\/v2\/product\/369654","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/digalco.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/digalco.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/digalco.com\/fr\/wp-json\/wp\/v2\/media\/369579"}],"wp:attachment":[{"href":"https:\/\/digalco.com\/fr\/wp-json\/wp\/v2\/media?parent=369654"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/digalco.com\/fr\/wp-json\/wp\/v2\/product_brand?post=369654"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/digalco.com\/fr\/wp-json\/wp\/v2\/product_cat?post=369654"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/digalco.com\/fr\/wp-json\/wp\/v2\/product_tag?post=369654"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}