{"id":369680,"date":"2026-05-20T11:09:25","date_gmt":"2026-05-20T09:09:25","guid":{"rendered":"https:\/\/digalco.com\/tienda\/eizo-flexscan-ev2316w-23-led-169-ricondizionato-1920x1080-it-15036\/"},"modified":"2026-05-25T13:24:30","modified_gmt":"2026-05-25T11:24:30","slug":"eizo-flexscan-ev2316w-23-led-169-ricondizionato-1920x1080-it-15036","status":"publish","type":"product","link":"https:\/\/digalco.com\/it\/tienda\/eizo-flexscan-ev2316w-23-led-169-ricondizionato-1920x1080-it-15036\/","title":{"rendered":"Eizo FlexScan EV2316W 23&#8221; Led 16:9 | Ricondizionato | 1920&#215;1080"},"content":{"rendered":"<p><strong>Schermo<\/strong><br \/>Led 23 &#8221; FullHD con Altoparlanti \u00b7  16:9  \u00b7 Risoluzione 1920&#215;1080<br \/>Punto passo 0.265 mm<br \/>Risposta 5 ms<br \/>Contrasto 1000:1<br \/>Luminosit\u00e0 250 cd\/m2<br \/>Angolo visione 170\u00b0v\/160\u00b0h<br \/><strong>Porte video<\/strong><br \/>VGA<br \/>Display Port<br \/>DVI<br \/><strong>Schermo specifico<\/strong><br \/>Supporto VESA<br \/>Peana<br \/>Regolabile in altezza<br \/><strong>Altri<\/strong><br \/>Imballaggio hR<br \/><strong>Dimensioni<\/strong><br \/>56x32x23 cm.<br \/><strong>Peso<\/strong><br \/>4.00 Kg.<br \/><strong>Specifiche aggiuntive<\/strong><br \/>L&#8217;Eizo FlexScan EV2316W \u00e8 un monitor LED professionale da 23 pollici del rinomato marchio giapponese Eizo, riferimento mondiale in termini di qualit\u00e0, ergonomia e affidabilit\u00e0 per ambienti di lavoro esigenti. Offre una risoluzione Full HD di 1920&#215;1080 pixel in formato 16:9 con un dot pitch di 0,265 mm, garantendo un&#8217;immagine nitida, dettagliata e confortevole per lunghe giornate di lavoro davanti allo schermo. Il tempo di risposta di 5 ms e il rapporto di contrasto di 1000:1 assicurano una visualizzazione chiara e ben definita su qualsiasi tipo di contenuto, supportati da una luminosit\u00e0 di 250 cd\/m\u00b2 che offre un&#8217;immagine equilibrata e riposante nelle condizioni di illuminazione tipiche di un ufficio. L&#8217;angolo di visione raggiunge i 170\u00b0 in verticale e 160\u00b0 in orizzontale, offrendo una visibilit\u00e0 corretta e confortevole da diverse posizioni di lavoro. Incorpora altoparlanti integrati che aggiungono funzionalit\u00e0 audio senza la necessit\u00e0 di periferiche aggiuntive. La connettivit\u00e0 include ingressi VGA, DisplayPort e DVI, oltre a due porte USB 2.0 per il collegamento di dispositivi aggiuntivi direttamente dal monitor. L&#8217;unit\u00e0 viene consegnata con cavo di alimentazione e cavo VGA inclusi, pronta per l&#8217;uso immediato. Un monitor professionale Eizo ricondizionato, sinonimo di qualit\u00e0 costruttiva e affidabilit\u00e0 comprovata, ideale per ambienti di lavoro che richiedono il meglio in termini di ergonomia visiva e prestazioni durature.<br \/>Buono stato estetico esterno. Pu\u00f2 presentare lievi segni d&#8217;uso sulla scocca. In caso di dubbi, chiamaci o usa la nostra chat per ricevere ulteriori informazioni o per richiedere maggiori dettagli.<br \/><strong>Commenti<\/strong><br \/><u>2xUSB 2.0 &#8211; Cavo di alimentazione e VGA inclusi<\/u><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Led 23 &#8221; FullHD con Altoparlanti \u00b7 16:9 \u00b7 Punto passo 0.265 mm \u00b7 Risposta 5 ms \u00b7 Contrasto 1000:1 \u00b7 Luminosit\u00e0 250 cd\/m2 \u00b7 VGA \u00b7 Display Port \u00b7 DVI \u00b7<br \/>\n<u>2xUSB 2.0 &#8211; Cavo di alimentazione e VGA inclusi<\/u> [&#8230;]<\/p>\n<p><a class=\"btn btn-secondary understrap-read-more-link\" href=\"https:\/\/digalco.com\/it\/tienda\/eizo-flexscan-ev2316w-23-led-169-ricondizionato-1920x1080-it-15036\/\">Leggi di pi\u00f9&#8230;<span class=\"screen-reader-text\"> from Eizo FlexScan EV2316W 23&#8221; Led 16:9 | Ricondizionato | 1920&#215;1080<\/span><\/a><\/p>\n","protected":false},"featured_media":369580,"template":"","meta":[],"product_brand":[3902],"product_cat":[3323,3215],"product_tag":[],"class_list":["post-369680","product","type-product","status-publish","has-post-thumbnail","product_brand-eizo","product_cat-monitor-23-it","product_cat-monitor-it","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"bundled_by":[],"bundle_stock_status":"outofstock","bundle_stock_quantity":0,"bundle_virtual":false,"bundle_layout":"","bundle_add_to_cart_form_location":"","bundle_editable_in_cart":false,"bundle_sold_individually_context":"","bundle_item_grouping":"","bundle_min_size":"","bundle_max_size":"","bundle_price":[],"bundled_items":[],"bundle_sell_ids":[],"exclude_global_add_ons":true,"addons":{"hdmi-upgrades":{"name":"Estensione cavo","type":"multiple_choice","position":0,"required":false,"title_format":"heading","default":"","description_enable":false,"description":"","placeholder_enable":false,"placeholder":"","display":"radiobutton","restrictions_type":"any_text","adjust_price":false,"price":"","price_type":"quantity_based","restrictions":false,"min":"0","max":"0","options":[{"label":"DisplayPort to DisplayPort cable 1,8 mts. [AMP00103]","price":"8.0000","price_type":"quantity_based","image":0,"visibility":true},{"label":"Dual Link DVI-D M\/M Cable 1,8 mts. [AMP00102]","price":"2.0000","price_type":"quantity_based","image":0,"visibility":true}]}},"df_price":82,"df_sale_price":"","df_regular_price":82,"df_image_link":"https:\/\/digalco.com\/wp-content\/uploads\/images\/product\/15036\/eizo00044_01-300x225.jpg","_links":{"self":[{"href":"https:\/\/digalco.com\/it\/wp-json\/wp\/v2\/product\/369680","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/digalco.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/digalco.com\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/digalco.com\/it\/wp-json\/wp\/v2\/media\/369580"}],"wp:attachment":[{"href":"https:\/\/digalco.com\/it\/wp-json\/wp\/v2\/media?parent=369680"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/digalco.com\/it\/wp-json\/wp\/v2\/product_brand?post=369680"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/digalco.com\/it\/wp-json\/wp\/v2\/product_cat?post=369680"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/digalco.com\/it\/wp-json\/wp\/v2\/product_tag?post=369680"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}